{"id":17025,"date":"2026-07-15T17:14:12","date_gmt":"2026-07-15T17:14:12","guid":{"rendered":"https:\/\/satoshibrother.com\/de\/ein-weiterer-defi-angriff-perpetual-dex-ostium-verliert-18-millionen-dollar-durch-oracle-angriff\/"},"modified":"2026-07-15T17:14:12","modified_gmt":"2026-07-15T17:14:12","slug":"ein-weiterer-defi-angriff-perpetual-dex-ostium-verliert-18-millionen-dollar-durch-oracle-angriff","status":"publish","type":"post","link":"https:\/\/satoshibrother.com\/de\/ein-weiterer-defi-angriff-perpetual-dex-ostium-verliert-18-millionen-dollar-durch-oracle-angriff\/","title":{"rendered":"Ein weiterer DeFi-Angriff: Perpetual DEX Ostium verliert 18 Millionen Dollar durch Oracle-Angriff"},"content":{"rendered":"<h2>Ostium erleidet Verlust durch Sicherheitsvorfall<\/h2>\n<p><strong>Ostium<\/strong> verlor am Mittwoch etwa <strong>18 Millionen Dollar<\/strong>, nachdem Angreifer einen Oracle-Signer-Schl\u00fcssel kompromittiert und den Preisfeed der dezentralen Perpetuals-B\u00f6rse manipuliert hatten, um gef\u00e4lschte Handelsgewinne zu generieren, so die Blockchain-Sicherheitsfirma <strong>Blockaid<\/strong>. In einem Post auf <em>X<\/em> erkl\u00e4rte Blockaid, der Angreifer habe einen registrierten <strong>PriceUpKeep-Forwarder<\/strong> sowie zuk\u00fcnftige autorisierte Oracle-Berichte verwendet, um k\u00fcnstliche Handelsgewinne zu erzeugen, was die mehrmillionenschwere Auszahlung \u2013 in Form des von Circle ausgegebenen Stablecoins <strong>USDC<\/strong> \u2013 aus dem Liquidit\u00e4tsvault von Ostium ausl\u00f6ste.<\/p>\n<blockquote><p>\u201eWir sind uns des Problems mit dem OLP-Vault bewusst\u201c, schrieb Ostium auf X. \u201eWir haben den gesamten Handel pausiert. Das Team untersucht den Vorfall.\u201c<\/p><\/blockquote>\n<p>Ostium, das auf <strong>Arbitrum<\/strong> basiert, bietet Perpetual Futures an, die an reale Verm\u00f6genswerte wie Aktien, Rohstoffe, Devisenm\u00e4rkte und Indizes gebunden sind. Es funktioniert als <strong>dezentrale B\u00f6rse (DEX)<\/strong>, was bedeutet, dass die Nutzer weitgehend die Kontrolle \u00fcber ihre Mittel behalten und keine personenbezogenen Daten bereitstellen m\u00fcssen.<\/p>\n<h2>Auswirkungen des Angriffs<\/h2>\n<p>Zum Zeitpunkt des Angriffs hielt das Protokoll etwa <strong>63 Millionen Dollar<\/strong> an insgesamt gesperrtem Wert, was bedeutet, dass der Angriff fast ein Drittel seiner Liquidit\u00e4t abgezogen hat. Der Vorfall ereignet sich in einem der schlimmsten Jahre f\u00fcr <strong>DeFi-Angriffe<\/strong>. <strong>DeFi<\/strong>, oder dezentrale Finanzen, bezieht sich auf Finanzanwendungen, die nativ auf Blockchain-Netzwerken ohne Drittanbieter wie Banken betrieben werden.<\/p>\n<p>In den ersten f\u00fcnf Monaten des Jahres 2026 wurden mehr als <strong>840 Millionen Dollar<\/strong> aus DeFi-Protokollen gestohlen, darunter <strong>292 Millionen Dollar<\/strong> von <strong>KelpDAO<\/strong> und <strong>285 Millionen Dollar<\/strong> von <strong>Drift Protocol<\/strong>. Hacker zielten auch im Juni auf <strong>Resolv Labs<\/strong> ab und stahlen \u00fcber <strong>25 Millionen Dollar<\/strong>. Sicherheitsexperten warnen, dass Fortschritte in der <strong>k\u00fcnstlichen Intelligenz<\/strong> die Entdeckung von Exploits beschleunigen.<\/p>\n<blockquote><p>&#8222;KI ist viel besser darin, Code zu \u00fcberpr\u00fcfen als die meisten Menschen und potenzielle Schwachstellen darin zu finden&#8220;, sagte <strong>Danny Jenkins<\/strong>, CEO und Mitbegr\u00fcnder von <strong>ThreatLocker<\/strong>, zuvor gegen\u00fcber <em>Decrypt<\/em>.<\/p><\/blockquote>\n<p>Jenkins erkl\u00e4rte, dass aktuelle KI-Systeme bereits die Entdeckung von Schwachstellen beschleunigen, w\u00e4hrend neuere Modelle wie <strong>Mythos<\/strong> diese F\u00e4higkeiten erheblich erweitern k\u00f6nnten, was er als ein bevorstehendes \u201egro\u00dfes Problem\u201c bezeichnete. <\/p>\n<blockquote><p>&#8222;Es wird nur eine Frage der Zeit sein, bis jemand B\u00f6ses Zugang dazu erh\u00e4lt&#8220;, f\u00fcgte er hinzu.<\/p><\/blockquote>\n<h2>Fortschritte in der KI und ihre Auswirkungen<\/h2>\n<p>Im Mai verwendete der Sicherheitsforscher <strong>Taylor Hornby<\/strong> <strong>Anthropic&#8217;s Claude Opus 4.8<\/strong>, um eine vier Jahre alte F\u00e4lschungsschwachstelle in <strong>Zcash<\/strong> zu identifizieren, was unterstreicht, wie fortschrittliche KI-Modelle zunehmend effektiv darin werden, komplexe Softwarefehler zu finden.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ostium erleidet Verlust durch Sicherheitsvorfall Ostium verlor am Mittwoch etwa 18 Millionen Dollar, nachdem Angreifer einen Oracle-Signer-Schl\u00fcssel kompromittiert und den Preisfeed der dezentralen Perpetuals-B\u00f6rse manipuliert hatten, um gef\u00e4lschte Handelsgewinne zu generieren, so die Blockchain-Sicherheitsfirma Blockaid. In einem Post auf X erkl\u00e4rte Blockaid, der Angreifer habe einen registrierten PriceUpKeep-Forwarder sowie zuk\u00fcnftige autorisierte Oracle-Berichte verwendet, um k\u00fcnstliche Handelsgewinne zu erzeugen, was die mehrmillionenschwere Auszahlung \u2013 in Form des von Circle ausgegebenen Stablecoins USDC \u2013 aus dem Liquidit\u00e4tsvault von Ostium ausl\u00f6ste. \u201eWir sind uns des Problems mit dem OLP-Vault bewusst\u201c, schrieb Ostium auf X. \u201eWir haben den gesamten Handel pausiert. Das Team untersucht<\/p>\n","protected":false},"author":3,"featured_media":17024,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[64],"tags":[428,8269,9996,65,10077,10584,77,7830],"class_list":["post-17025","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-hack","tag-arbitrum","tag-blockaid","tag-drift-protocol","tag-hack","tag-kelpdao","tag-resolv-labs","tag-usdc","tag-zcash"],"yoast_description":"Der DEX Ostium erleidet einen Verlust von 18 Millionen Dollar aufgrund eines Oracle-Angriffs, der Preisfeeds manipuliert und die Schwachstellen im DeFi-Sektor angesichts zunehmender Sicherheitsbedrohungen aufzeigt.","_links":{"self":[{"href":"https:\/\/satoshibrother.com\/de\/wp-json\/wp\/v2\/posts\/17025","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/satoshibrother.com\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/satoshibrother.com\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/satoshibrother.com\/de\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/satoshibrother.com\/de\/wp-json\/wp\/v2\/comments?post=17025"}],"version-history":[{"count":0,"href":"https:\/\/satoshibrother.com\/de\/wp-json\/wp\/v2\/posts\/17025\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/satoshibrother.com\/de\/wp-json\/wp\/v2\/media\/17024"}],"wp:attachment":[{"href":"https:\/\/satoshibrother.com\/de\/wp-json\/wp\/v2\/media?parent=17025"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/satoshibrother.com\/de\/wp-json\/wp\/v2\/categories?post=17025"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/satoshibrother.com\/de\/wp-json\/wp\/v2\/tags?post=17025"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}