{"id":10215,"count":1,"description":"Die Handelsvolumina auf den Figur-M\u00e4rkten haben Rekordwerte erreicht. Entdecken Sie die Trends und einzigartigen Chancen, die sich daraus ergeben.","link":"https:\/\/satoshibrother.com\/de\/tag\/figure-markets\/","name":"Figure Markets","slug":"figure-markets","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/satoshibrother.com\/de\/wp-json\/wp\/v2\/tags\/10215","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/satoshibrother.com\/de\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/satoshibrother.com\/de\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/satoshibrother.com\/de\/wp-json\/wp\/v2\/posts?tags=10215"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}