{"id":13286,"date":"2026-02-11T08:22:53","date_gmt":"2026-02-11T08:22:53","guid":{"rendered":"https:\/\/satoshibrother.com\/es\/goldman-sachs-invierte-152-millones-en-xrp\/"},"modified":"2026-02-11T08:22:53","modified_gmt":"2026-02-11T08:22:53","slug":"goldman-sachs-invierte-152-millones-en-xrp","status":"publish","type":"post","link":"https:\/\/satoshibrother.com\/es\/goldman-sachs-invierte-152-millones-en-xrp\/","title":{"rendered":"Goldman Sachs invierte $152 millones en XRP"},"content":{"rendered":"<h2>Inversi\u00f3n de Goldman Sachs en Criptomonedas<\/h2>\n<p><strong>Goldman Sachs<\/strong> ha asignado m\u00e1s de un cuarto de mil millones de d\u00f3lares a <strong>XRP<\/strong> y <strong>Solana<\/strong>. Su \u00faltima presentaci\u00f3n 13F ante la <strong>SEC<\/strong> revela que el banco de inversi\u00f3n tiene <strong>$152 millones<\/strong> en participaciones de ETF de XRP y <strong>$108 millones<\/strong> en participaciones de ETF de Solana (SOL).<\/p>\n<blockquote><p>\u00abNotablemente, seg\u00fan informes recientes, ejecutivos de Goldman Sachs estuvieron en la Casa Blanca negociando el futuro de los rendimientos de las stablecoins el martes.\u00bb<\/p><\/blockquote>\n<p>Como inform\u00f3 U.Today, <strong>Stuart Alderoty<\/strong> de Ripple tambi\u00e9n estuvo presente durante la reuni\u00f3n. El CEO <strong>David Solomon<\/strong> est\u00e1 programado para hablar en el <strong>World Liberty Financial Forum<\/strong> en Palm Beach la pr\u00f3xima semana.<\/p>\n<h2>Detalles de la Inversi\u00f3n<\/h2>\n<p>Seg\u00fan la presentaci\u00f3n, que cubre el cuarto trimestre de 2025, las nuevas posiciones de Goldman se mantienen completamente a trav\u00e9s de <strong>ETFs de spot<\/strong> en EE. UU., en lugar de la propiedad directa de tokens. La inversi\u00f3n de <strong>$152 millones<\/strong> de Goldman en XRP se distribuye entre varios emisores:<\/p>\n<ul>\n<li>Bitwise XRP ETF ($39.8 millones)<\/li>\n<li>Franklin XRP Trust ($38.5 millones)<\/li>\n<li>Grayscale XRP Trust ($38.0 millones)<\/li>\n<li>21Shares XRP ETF ($35.9 millones)<\/li>\n<\/ul>\n<p>Al mismo tiempo, el banco revel\u00f3 una posici\u00f3n de <strong>$108 millones<\/strong> en Solana, con la mayor parte asignada al:<\/p>\n<ul>\n<li>Bitwise Solana ETF ($45.4 millones)<\/li>\n<li>Grayscale Solana Trust ($35.7 millones)<\/li>\n<\/ul>\n<h2>Rotaci\u00f3n de Activos<\/h2>\n<p>La entrada en XRP y Solana parece estar financiada, al menos en parte, por una rotaci\u00f3n fuera de <strong>Bitcoin<\/strong>. Los datos de la misma presentaci\u00f3n indican que Goldman redujo sus participaciones en ETFs de Bitcoin spot en aproximadamente un <strong>40%<\/strong> en el cuarto trimestre de 2025. Sin embargo, el banco a\u00fan mantiene posiciones sustanciales:<\/p>\n<ul>\n<li><strong>$1.1 mil millones<\/strong> en Bitcoin<\/li>\n<li><strong>$1 mil millones<\/strong> en Ethereum<\/li>\n<\/ul>\n<p>Las compras recientes muestran que los analistas de Goldman ven un mayor potencial de crecimiento en <em>altcoins<\/em> enfocadas en la utilidad.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Inversi\u00f3n de Goldman Sachs en Criptomonedas Goldman Sachs ha asignado m\u00e1s de un cuarto de mil millones de d\u00f3lares a XRP y Solana. Su \u00faltima presentaci\u00f3n 13F ante la SEC revela que el banco de inversi\u00f3n tiene $152 millones en participaciones de ETF de XRP y $108 millones en participaciones de ETF de Solana (SOL). \u00abNotablemente, seg\u00fan informes recientes, ejecutivos de Goldman Sachs estuvieron en la Casa Blanca negociando el futuro de los rendimientos de las stablecoins el martes.\u00bb Como inform\u00f3 U.Today, Stuart Alderoty de Ripple tambi\u00e9n estuvo presente durante la reuni\u00f3n. El CEO David Solomon est\u00e1 programado para hablar<\/p>\n","protected":false},"author":3,"featured_media":13285,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[23,124,106],"tags":[11,8738,13,800,9740,25,9741,8,24,115,4034],"class_list":["post-13286","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-legal","category-ripple","category-solana","tag-bitcoin","tag-bitwise-xrp-etf","tag-ethereum","tag-goldman-sachs","tag-grayscale-solana-trust","tag-legal","tag-palm-beach","tag-ripple","tag-sec","tag-solana","tag-stuart-alderoty"],"yoast_description":"Goldman Sachs informa sobre $152 millones en XRP y $108 millones en participaciones de ETF de Solana, cambiando su enfoque de Bitcoin hacia altcoins impulsadas por la utilidad.","_links":{"self":[{"href":"https:\/\/satoshibrother.com\/es\/wp-json\/wp\/v2\/posts\/13286","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/satoshibrother.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/satoshibrother.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/satoshibrother.com\/es\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/satoshibrother.com\/es\/wp-json\/wp\/v2\/comments?post=13286"}],"version-history":[{"count":0,"href":"https:\/\/satoshibrother.com\/es\/wp-json\/wp\/v2\/posts\/13286\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/satoshibrother.com\/es\/wp-json\/wp\/v2\/media\/13285"}],"wp:attachment":[{"href":"https:\/\/satoshibrother.com\/es\/wp-json\/wp\/v2\/media?parent=13286"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/satoshibrother.com\/es\/wp-json\/wp\/v2\/categories?post=13286"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/satoshibrother.com\/es\/wp-json\/wp\/v2\/tags?post=13286"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}