{"id":17028,"date":"2026-07-15T17:14:12","date_gmt":"2026-07-15T17:14:12","guid":{"rendered":"https:\/\/satoshibrother.com\/es\/otra-explotacion-defi-el-dex-ostium-pierde-18-millones-en-un-ataque-de-oracle\/"},"modified":"2026-07-15T17:14:12","modified_gmt":"2026-07-15T17:14:12","slug":"otra-explotacion-defi-el-dex-ostium-pierde-18-millones-en-un-ataque-de-oracle","status":"publish","type":"post","link":"https:\/\/satoshibrother.com\/es\/otra-explotacion-defi-el-dex-ostium-pierde-18-millones-en-un-ataque-de-oracle\/","title":{"rendered":"Otra Explotaci\u00f3n DeFi: El DEX Ostium Pierde $18 Millones en un Ataque de Oracle"},"content":{"rendered":"<h2>Ostium Sufre P\u00e9rdidas Significativas<\/h2>\n<p>Ostium perdi\u00f3 aproximadamente <strong>$18 millones<\/strong> el mi\u00e9rcoles despu\u00e9s de que los atacantes comprometieran una <strong>clave de firmante de oracle<\/strong> y manipularan el feed de precios del intercambio descentralizado de futuros perpetuos para generar <strong>ganancias comerciales falsas<\/strong>, seg\u00fan la firma de seguridad blockchain <em>Blockaid<\/em>. En una publicaci\u00f3n en X, Blockaid inform\u00f3 que el atacante utiliz\u00f3 un reenv\u00edo registrado de <strong>PriceUpKeep<\/strong> y reportes de oracle autorizados con fecha futura para crear ganancias comerciales artificiales, lo que desencaden\u00f3 el pago de varios millones en forma de la stablecoin <strong>USDC<\/strong> emitida por Circle desde el vault de liquidez de Ostium. \u00abEstamos al tanto del problema con el vault OLP\u00bb, escribi\u00f3 Ostium en X. \u00abHemos pausado todas las operaciones. El equipo est\u00e1 investigando.\u00bb<\/p>\n<h2>Detalles del Intercambio y el Ataque<\/h2>\n<p>Construido sobre <strong>Arbitrum<\/strong>, Ostium ofrece futuros perpetuos vinculados a activos del mundo real, incluidos acciones, materias primas, mercados de divisas e \u00edndices. Opera como un <strong>intercambio descentralizado (DEX)<\/strong>, lo que significa que los usuarios mantienen en gran medida el control de sus fondos y no proporcionan informaci\u00f3n personal identificable. En el momento del ataque, el protocolo ten\u00eda aproximadamente <strong>$63 millones<\/strong> en valor total bloqueado, lo que significa que la explotaci\u00f3n dren\u00f3 cerca de un tercio de su liquidez.<\/p>\n<h2>Aumento de Explotaciones en el Sector DeFi<\/h2>\n<p>Este ataque se produce en medio de uno de los peores a\u00f1os registrados para las explotaciones en el sector <strong>DeFi<\/strong>. DeFi, o finanzas descentralizadas, se refiere a aplicaciones financieras que operan de manera nativa en redes blockchain, sin intermediarios de terceros como bancos. M\u00e1s de <strong>$840 millones<\/strong> fueron robados de protocolos DeFi en los primeros cinco meses de 2026, incluidos <strong>$292 millones<\/strong> robados de <em>KelpDAO<\/em> y <strong>$285 millones<\/strong> de <em>Drift Protocol<\/em>. Adem\u00e1s, los hackers atacaron a <em>Resolv Labs<\/em> en junio, robando m\u00e1s de <strong>$25 millones<\/strong>.<\/p>\n<h2>Impacto de la Inteligencia Artificial en la Seguridad<\/h2>\n<p>Los expertos en seguridad advierten que los avances en <strong>inteligencia artificial<\/strong> est\u00e1n acelerando el descubrimiento de vulnerabilidades. \u00ab<\/p>\n<blockquote><p>La IA es mucho mejor revisando c\u00f3digo que la mayor\u00eda de las personas y encontrando vulnerabilidades potenciales en \u00e9l<\/p><\/blockquote>\n<p>\u00ab, afirm\u00f3 <strong>Danny Jenkins<\/strong>, CEO y cofundador de <em>ThreatLocker<\/em>, en una entrevista con <em>Decrypt<\/em>. Jenkins se\u00f1al\u00f3 que los sistemas de IA actuales ya est\u00e1n acelerando el descubrimiento de vulnerabilidades, mientras que modelos m\u00e1s nuevos como <strong>Mythos<\/strong> podr\u00edan expandir significativamente esas capacidades, describi\u00e9ndolo como un <strong>\u00abgran problema\u00bb<\/strong> inminente. \u00ab<\/p>\n<blockquote><p>Solo ser\u00e1 cuesti\u00f3n de tiempo hasta que alguien malo tenga acceso a ello<\/p><\/blockquote>\n<p>\u00ab, advirti\u00f3. En mayo, el investigador de seguridad <strong>Taylor Hornby<\/strong> utiliz\u00f3 <em>Claude Opus 4.8<\/em> de <em>Anthropic<\/em> para identificar una vulnerabilidad de falsificaci\u00f3n de cuatro a\u00f1os en <em>Zcash<\/em>, subrayando c\u00f3mo los modelos de IA de frontera se est\u00e1n volviendo cada vez m\u00e1s efectivos para encontrar fallos complejos en el software.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ostium Sufre P\u00e9rdidas Significativas Ostium perdi\u00f3 aproximadamente $18 millones el mi\u00e9rcoles despu\u00e9s de que los atacantes comprometieran una clave de firmante de oracle y manipularan el feed de precios del intercambio descentralizado de futuros perpetuos para generar ganancias comerciales falsas, seg\u00fan la firma de seguridad blockchain Blockaid. En una publicaci\u00f3n en X, Blockaid inform\u00f3 que el atacante utiliz\u00f3 un reenv\u00edo registrado de PriceUpKeep y reportes de oracle autorizados con fecha futura para crear ganancias comerciales artificiales, lo que desencaden\u00f3 el pago de varios millones en forma de la stablecoin USDC emitida por Circle desde el vault de liquidez de Ostium.<\/p>\n","protected":false},"author":3,"featured_media":17027,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[64],"tags":[428,8269,9997,65,10078,10584,77,7830],"class_list":["post-17028","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-hack","tag-arbitrum","tag-blockaid","tag-drift-protocol","tag-hack","tag-kelpdao","tag-resolv-labs","tag-usdc","tag-zcash"],"yoast_description":"El DEX Ostium sufre una p\u00e9rdida de $18 millones debido a un ataque de oracle que manipula los feeds de precios, destacando las vulnerabilidades en el sector DeFi en medio de crecientes amenazas de seguridad.","_links":{"self":[{"href":"https:\/\/satoshibrother.com\/es\/wp-json\/wp\/v2\/posts\/17028","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/satoshibrother.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/satoshibrother.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/satoshibrother.com\/es\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/satoshibrother.com\/es\/wp-json\/wp\/v2\/comments?post=17028"}],"version-history":[{"count":0,"href":"https:\/\/satoshibrother.com\/es\/wp-json\/wp\/v2\/posts\/17028\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/satoshibrother.com\/es\/wp-json\/wp\/v2\/media\/17027"}],"wp:attachment":[{"href":"https:\/\/satoshibrother.com\/es\/wp-json\/wp\/v2\/media?parent=17028"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/satoshibrother.com\/es\/wp-json\/wp\/v2\/categories?post=17028"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/satoshibrother.com\/es\/wp-json\/wp\/v2\/tags?post=17028"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}