{"id":18014,"date":"2026-09-01T16:52:12","date_gmt":"2026-09-01T16:52:12","guid":{"rendered":"https:\/\/satoshibrother.com\/es\/bofa-citi-y-goldman-sachs-entre-21-instituciones-que-planean-lanzar-una-stablecoin\/"},"modified":"2026-09-01T16:52:12","modified_gmt":"2026-09-01T16:52:12","slug":"bofa-citi-y-goldman-sachs-entre-21-instituciones-que-planean-lanzar-una-stablecoin","status":"publish","type":"post","link":"https:\/\/satoshibrother.com\/es\/bofa-citi-y-goldman-sachs-entre-21-instituciones-que-planean-lanzar-una-stablecoin\/","title":{"rendered":"BofA, Citi y Goldman Sachs entre 21 instituciones que planean lanzar una stablecoin"},"content":{"rendered":"<h2>Iniciativa de Stablecoins por Instituciones Financieras<\/h2>\n<p>Un grupo de <strong>21 importantes instituciones financieras<\/strong>, entre las que se encuentran <strong>Bank of America<\/strong>, <strong>Goldman Sachs<\/strong>, <strong>Citi<\/strong>, <strong>Deutsche Bank<\/strong>, <strong>UBS<\/strong>, <strong>Santander<\/strong>, <strong>MUFG<\/strong> y <strong>Fidelity Investments<\/strong>, planea establecer una nueva empresa dedicada al desarrollo y emisi\u00f3n de <em>stablecoins<\/em>. Esta iniciativa representa un claro impulso de las finanzas tradicionales hacia los <strong>d\u00f3lares digitales<\/strong>, en un momento en que se est\u00e1n formando marcos regulatorios adecuados.<\/p>\n<h2>Detalles del Stablecoin<\/h2>\n<p>La empresa se centrar\u00e1 inicialmente en un <strong>stablecoin respaldado por el d\u00f3lar estadounidense<\/strong>, con planes de expandirse a otras monedas del G7, siendo la oferta en euros su siguiente prioridad. Se espera que el stablecoin denominado en d\u00f3lares estadounidenses se lance en la <strong>primera mitad de 2027<\/strong>, sujeto a la formaci\u00f3n de la empresa y a otras condiciones.<\/p>\n<p>El consorcio ha declarado que su stablecoin estar\u00e1 dirigido a los <strong>mercados mayoristas, institucionales y minoristas<\/strong>, y se utilizar\u00e1 en casos como <strong>pagos transfronterizos<\/strong> y <strong>liquidaci\u00f3n de activos digitales<\/strong>. Esta iniciativa busca cumplir tanto con la <strong>Ley GENIUS<\/strong> de EE. UU. como con el <strong>Reglamento de Mercados en Criptoactivos (MiCA)<\/strong> de la Uni\u00f3n Europea, donde sea aplicable.<\/p>\n<h2>Contexto y Crecimiento de Stablecoins<\/h2>\n<p>La creaci\u00f3n de esta empresa se basa en una iniciativa anunciada en octubre pasado, cuando un grupo inicial de <strong>10 bancos<\/strong> expres\u00f3 su inter\u00e9s en explorar una forma de dinero digital respaldada por reservas 1:1 disponibles en <em>blockchains<\/em> p\u00fablicas. Desde entonces, el consorcio ha m\u00e1s que duplicado su tama\u00f1o, incorporando instituciones financieras de Am\u00e9rica del Norte, Europa, Asia Oriental, Medio Oriente y \u00c1frica.<\/p>\n<p>Este movimiento se produce en un contexto donde los stablecoins han crecido considerablemente en los \u00faltimos a\u00f1os, impulsados por la aprobaci\u00f3n de la Ley GENIUS y el MiCA, que han creado caminos regulatorios m\u00e1s claros para su adopci\u00f3n. Por otro lado, <strong>Singapur<\/strong> est\u00e1 considerando permitir stablecoins transfronterizos emitidos conjuntamente en su r\u00e9gimen regulatorio, revisando su decisi\u00f3n anterior de restringir el marco a la emisi\u00f3n nacional.<\/p>\n<h2>Inter\u00e9s Institucional en Stablecoins<\/h2>\n<p>El inter\u00e9s institucional en las stablecoins ya se estaba gestando a principios de <strong>2025<\/strong>, cuando una encuesta de <strong>Fireblocks<\/strong> a 295 ejecutivos revel\u00f3 que el <strong>90%<\/strong> de los encuestados estaban utilizando o planeaban utilizar stablecoins. Desde entonces, importantes instituciones financieras han ampliado su presencia en este sector. Por ejemplo, la subsidiaria de cripto de <strong>Soci\u00e9t\u00e9 G\u00e9n\u00e9rale<\/strong> ha emitido stablecoins denominados en euros y d\u00f3lares, mientras que <strong>Fidelity<\/strong> lanz\u00f3 recientemente su stablecoin <strong>FIDD<\/strong>, vinculada al d\u00f3lar estadounidense. Adem\u00e1s, el mes pasado, <strong>Standard Chartered<\/strong> respald\u00f3 una empresa de stablecoin en d\u00f3lares en Hong Kong.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Iniciativa de Stablecoins por Instituciones Financieras Un grupo de 21 importantes instituciones financieras, entre las que se encuentran Bank of America, Goldman Sachs, Citi, Deutsche Bank, UBS, Santander, MUFG y Fidelity Investments, planea establecer una nueva empresa dedicada al desarrollo y emisi\u00f3n de stablecoins. Esta iniciativa representa un claro impulso de las finanzas tradicionales hacia los d\u00f3lares digitales, en un momento en que se est\u00e1n formando marcos regulatorios adecuados. Detalles del Stablecoin La empresa se centrar\u00e1 inicialmente en un stablecoin respaldado por el d\u00f3lar estadounidense, con planes de expandirse a otras monedas del G7, siendo la oferta en euros su<\/p>\n","protected":false},"author":3,"featured_media":18013,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[23],"tags":[1343,7765,1647,218,474,859,800,25,145,8878,6088,469,2955,981,7726],"class_list":["post-18014","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-legal","tag-bank-of-america","tag-citi","tag-deutsche-bank","tag-fidelity","tag-fireblocks","tag-genius-act","tag-goldman-sachs","tag-legal","tag-mica","tag-mufg","tag-santander","tag-singapore","tag-societe-generale","tag-standard-chartered","tag-ubs"],"yoast_description":"Un consorcio de 21 instituciones financieras, incluyendo BofA y Goldman Sachs, se embarca en el desarrollo de stablecoins, comenzando con una oferta en d\u00f3lares estadounidenses y planeando expandirse a monedas del G7.","_links":{"self":[{"href":"https:\/\/satoshibrother.com\/es\/wp-json\/wp\/v2\/posts\/18014","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/satoshibrother.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/satoshibrother.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/satoshibrother.com\/es\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/satoshibrother.com\/es\/wp-json\/wp\/v2\/comments?post=18014"}],"version-history":[{"count":0,"href":"https:\/\/satoshibrother.com\/es\/wp-json\/wp\/v2\/posts\/18014\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/satoshibrother.com\/es\/wp-json\/wp\/v2\/media\/18013"}],"wp:attachment":[{"href":"https:\/\/satoshibrother.com\/es\/wp-json\/wp\/v2\/media?parent=18014"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/satoshibrother.com\/es\/wp-json\/wp\/v2\/categories?post=18014"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/satoshibrother.com\/es\/wp-json\/wp\/v2\/tags?post=18014"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}