{"id":4310,"date":"2025-05-12T06:13:21","date_gmt":"2025-05-12T06:13:21","guid":{"rendered":"https:\/\/satoshibrother.com\/es\/metaplanet-supera-a-el-salvador-en-tenencias-de-bitcoin\/"},"modified":"2025-05-12T06:13:21","modified_gmt":"2025-05-12T06:13:21","slug":"metaplanet-supera-a-el-salvador-en-tenencias-de-bitcoin","status":"publish","type":"post","link":"https:\/\/satoshibrother.com\/es\/metaplanet-supera-a-el-salvador-en-tenencias-de-bitcoin\/","title":{"rendered":"Metaplanet supera a El Salvador en tenencias de Bitcoin"},"content":{"rendered":"<h2>Incremento en la Tesorer\u00eda de Metaplanet<\/h2>\n<p>La firma de inversi\u00f3n japonesa <strong>Metaplanet<\/strong> ha incrementado su tesorer\u00eda de Bitcoin en <strong>129 millones de d\u00f3lares<\/strong>, superando as\u00ed las tenencias del pa\u00eds acumulador de esta criptomoneda, <strong>El Salvador<\/strong>. <\/p>\n<blockquote><p>\u00abMetaplanet ahora posee m\u00e1s Bitcoin que El Salvador. Desde humildes comienzos, ahora rivalizamos con naciones-estado; apenas estamos comenzando\u00bb,<\/p><\/blockquote>\n<p> declar\u00f3 <strong>Simon Gerovich<\/strong>, CEO de la empresa, en X tras anunciar la \u00faltima adquisici\u00f3n.<\/p>\n<h2>Detalles de la Adquisici\u00f3n<\/h2>\n<p>El 12 de mayo, la firma cotizada en Tokio inform\u00f3 que hab\u00eda adquirido <strong>1,241 Bitcoin<\/strong> a un precio de <strong>14.8 millones de yenes<\/strong> (equivalente a <strong>101,843 d\u00f3lares<\/strong> por moneda). En total, esta compra, realizada a su precio m\u00e1s alto de adquisici\u00f3n, equivale a aproximadamente <strong>129 millones de d\u00f3lares<\/strong> a los precios de mercado actuales.<\/p>\n<p>Esto eleva las tenencias totales de Metaplanet a <strong>6,796 Bitcoin<\/strong>, valorados en aproximadamente <strong>707 millones de d\u00f3lares<\/strong>, con un precio de compra promedio de <strong>91,000 d\u00f3lares<\/strong> por Bitcoin.<\/p>\n<h2>Estrategia de Acumulaci\u00f3n<\/h2>\n<p>Metaplanet inici\u00f3 su estrategia de acumulaci\u00f3n de BTC en <strong>abril de 2024<\/strong>. El Salvador, por su parte, se sit\u00faa como el sexto mayor tenedor nacional del activo, con <strong>6,714 Bitcoin<\/strong> valorados en cerca de <strong>642 millones de d\u00f3lares<\/strong>, seg\u00fan la <strong>Oficina Nacional de Bitcoin<\/strong>.<\/p>\n<p>La firma de inversi\u00f3n tambi\u00e9n report\u00f3 un rendimiento de Bitcoin, que mide el cambio porcentual en las tenencias de Bitcoin por acci\u00f3n totalmente diluida, del <strong>38%<\/strong> para el trimestre actual. En el primer trimestre de <strong>2025<\/strong>, logr\u00f3 un rendimiento del <strong>95.6%<\/strong>.<\/p>\n<p>Metaplanet ha adoptado una postura m\u00e1s agresiva en la acumulaci\u00f3n de este activo en los \u00faltimos meses. El <strong>7 de mayo<\/strong> compr\u00f3 <strong>5,555 Bitcoin<\/strong>; durante abril realiz\u00f3 cuatro compras que suman <strong>18,586 BTC<\/strong>; y en marzo realiz\u00f3 seis compras totalizando <strong>18,925 BTC<\/strong>, cada una superando a la previa. Actualmente, Metaplanet es el mayor tenedor de Bitcoin en Asia y el d\u00e9cimo a nivel mundial, seg\u00fan BiTBO.<\/p>\n<h2>Especulaciones sobre Nuevas Compras<\/h2>\n<p>Por otro lado, <strong>Michael Saylor<\/strong> insinu\u00f3 una nueva compra por parte de su firma <strong>Strategy<\/strong> el <strong>12 de mayo<\/strong>, al publicar una captura de pantalla del gr\u00e1fico <strong>\u00abSaylor Tracker\u00bb<\/strong>, que sigue la cartera de tesorer\u00eda de Bitcoin de la firma. <\/p>\n<blockquote><p>\u00abConecta los puntos\u00bb<\/p><\/blockquote>\n<p> fue su comentario, lo que ha generado especulaciones, ya que Saylor ha hecho publicaciones similares en el pasado, seguidas de anuncios de adquisici\u00f3n de BTC.<\/p>\n<p>En la actualidad, Strategy posee <strong>555,450 BTC<\/strong>, valorados en aproximadamente <strong>57.8 mil millones de d\u00f3lares<\/strong> a precios actuales, seg\u00fan el rastreador.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Incremento en la Tesorer\u00eda de Metaplanet La firma de inversi\u00f3n japonesa Metaplanet ha incrementado su tesorer\u00eda de Bitcoin en 129 millones de d\u00f3lares, superando as\u00ed las tenencias del pa\u00eds acumulador de esta criptomoneda, El Salvador. \u00abMetaplanet ahora posee m\u00e1s Bitcoin que El Salvador. Desde humildes comienzos, ahora rivalizamos con naciones-estado; apenas estamos comenzando\u00bb, declar\u00f3 Simon Gerovich, CEO de la empresa, en X tras anunciar la \u00faltima adquisici\u00f3n. Detalles de la Adquisici\u00f3n El 12 de mayo, la firma cotizada en Tokio inform\u00f3 que hab\u00eda adquirido 1,241 Bitcoin a un precio de 14.8 millones de yenes (equivalente a 101,843 d\u00f3lares por moneda).<\/p>\n","protected":false},"author":3,"featured_media":4309,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[15],"tags":[11,1300,35,506,312,1836,318],"class_list":["post-4310","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-bitcoin","tag-bitcoin","tag-el-salvador","tag-japan","tag-metaplanet","tag-michael-saylor","tag-simon-gerovich","tag-strategy"],"yoast_description":"Metaplanet ha superado a El Salvador en tenencias de Bitcoin, con 6,796 BTC valorados en 707 millones de d\u00f3lares, reflejando sus agresivas estrategias de acumulaci\u00f3n.","_links":{"self":[{"href":"https:\/\/satoshibrother.com\/es\/wp-json\/wp\/v2\/posts\/4310","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/satoshibrother.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/satoshibrother.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/satoshibrother.com\/es\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/satoshibrother.com\/es\/wp-json\/wp\/v2\/comments?post=4310"}],"version-history":[{"count":0,"href":"https:\/\/satoshibrother.com\/es\/wp-json\/wp\/v2\/posts\/4310\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/satoshibrother.com\/es\/wp-json\/wp\/v2\/media\/4309"}],"wp:attachment":[{"href":"https:\/\/satoshibrother.com\/es\/wp-json\/wp\/v2\/media?parent=4310"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/satoshibrother.com\/es\/wp-json\/wp\/v2\/categories?post=4310"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/satoshibrother.com\/es\/wp-json\/wp\/v2\/tags?post=4310"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}