{"id":15362,"date":"2026-05-12T21:22:11","date_gmt":"2026-05-12T21:22:11","guid":{"rendered":"https:\/\/satoshibrother.com\/fr\/exodus-wallet-se-separe-de-bitcoin-pour-renforcer-ses-activites-de-paiement\/"},"modified":"2026-05-12T21:22:11","modified_gmt":"2026-05-12T21:22:11","slug":"exodus-wallet-se-separe-de-bitcoin-pour-renforcer-ses-activites-de-paiement","status":"publish","type":"post","link":"https:\/\/satoshibrother.com\/fr\/exodus-wallet-se-separe-de-bitcoin-pour-renforcer-ses-activites-de-paiement\/","title":{"rendered":"Exodus Wallet se s\u00e9pare de Bitcoin pour renforcer ses activit\u00e9s de paiement"},"content":{"rendered":"<h2>Exodus Wallet : Ventes de Bitcoins et Acquisition Strat\u00e9gique<\/h2>\n<p>Exodus Wallet a vendu <strong>1 076 bitcoins<\/strong> au premier trimestre 2026 pour financer son acquisition de <strong>175 millions de dollars<\/strong> de l&rsquo;activit\u00e9 de paiements de W3C. Exodus Movement (NYSE: EXOD), le d\u00e9veloppeur du portefeuille auto-g\u00e9r\u00e9 Exodus, a r\u00e9duit ses avoirs en BTC de <strong>1 704 \u00e0 628 pi\u00e8ces<\/strong>, diminuant ainsi la valeur de sa tr\u00e9sorerie de <strong>149,2 millions de dollars \u00e0 42,8 millions de dollars<\/strong>. Parall\u00e8lement, l&rsquo;entreprise a ajout\u00e9 <strong>5 068 tokens Solana<\/strong> durant la m\u00eame p\u00e9riode. Au total, Exodus a r\u00e9alis\u00e9 des ventes de cryptomonnaies s&rsquo;\u00e9levant \u00e0 <strong>73,2 millions de dollars<\/strong> durant le trimestre, tout en n&rsquo;achetant que <strong>962 000 dollars<\/strong>.<\/p>\n<blockquote>\n<p>\u00ab\u00a0Au premier trimestre 2026, la soci\u00e9t\u00e9 a continu\u00e9 \u00e0 vendre des actifs num\u00e9riques pour se pr\u00e9parer \u00e0 la prochaine distribution li\u00e9e \u00e0 la cl\u00f4ture de W3C, et a mis de c\u00f4t\u00e9 plus de <strong>70 millions de dollars<\/strong> en r\u00e9serves en dollars am\u00e9ricains pour ces obligations,\u00a0\u00bb indique le rapport trimestriel.<\/p>\n<\/blockquote>\n<p>Les liquidit\u00e9s, \u00e9quivalents et stablecoins ont augment\u00e9 \u00e0 <strong>74,4 millions de dollars<\/strong>, contre <strong>5,2 millions de dollars<\/strong> \u00e0 la fin de l&rsquo;ann\u00e9e pr\u00e9c\u00e9dente.<\/p>\n<h2>Acquisition de Monavate et Baanx<\/h2>\n<p>Exodus a finalis\u00e9 son acquisition de <strong>Monavate<\/strong> et <strong>Baanx<\/strong> le 1er mai, deux filiales de paiements de W3C Corp, pour un total de <strong>175 millions de dollars<\/strong>. Cet accord permet d&rsquo;int\u00e9grer une infrastructure d&rsquo;\u00e9mission de cartes et de paiements directement dans le portefeuille auto-g\u00e9r\u00e9 d&rsquo;Exodus. Baanx fournit l&rsquo;infrastructure de cartes de d\u00e9bit crypto, tandis que Monavate g\u00e8re les programmes de cartes.<\/p>\n<p>Cette strat\u00e9gie s&rsquo;inscrit dans le cadre de l&rsquo;annonce ant\u00e9rieure d&rsquo;Exodus concernant un <strong>stablecoin enti\u00e8rement r\u00e9serv\u00e9<\/strong> et adoss\u00e9 au dollar, d\u00e9velopp\u00e9 en collaboration avec MoonPay et M0, qui soutiendra la fonctionnalit\u00e9 Exodus Pay dans l&rsquo;application. <strong>XO Cash<\/strong>, un kit d&rsquo;outils de stablecoin bas\u00e9 sur Solana, d\u00e9j\u00e0 op\u00e9rationnel, permet aux agents IA de d\u00e9penser de l&rsquo;argent via les rails Visa sans exposer les cl\u00e9s priv\u00e9es des utilisateurs.<\/p>\n<h2>R\u00e9sultats Financiers et Perspectives<\/h2>\n<p>Les revenus du premier trimestre ont chut\u00e9 de <strong>36,8 %<\/strong> pour atteindre <strong>22,7 millions de dollars<\/strong>, contre <strong>36 millions de dollars<\/strong> un an plus t\u00f4t. L&rsquo;agr\u00e9gation d&rsquo;\u00e9changes, principale source de revenus de l&rsquo;entreprise, a diminu\u00e9 de <strong>13,8 millions de dollars<\/strong> alors que les volumes de trading des utilisateurs se tarissaient. La perte nette s&rsquo;est \u00e9largie \u00e0 <strong>32,1 millions de dollars<\/strong>, contre <strong>12,9 millions de dollars<\/strong>, en partie en raison d&rsquo;une perte de <strong>36,4 millions de dollars<\/strong> sur les avoirs en crypto, alors que le bitcoin a chut\u00e9 de <strong>23 %<\/strong> et Solana de plus de <strong>34 %<\/strong> durant le trimestre.<\/p>\n<p>Exodus est le seul fournisseur de portefeuille auto-g\u00e9r\u00e9 cot\u00e9 en bourse \u00e0 construire activement une pile de paiements compl\u00e8te. Le nombre d&rsquo;utilisateurs actifs mensuels a chut\u00e9 \u00e0 <strong>1,5 million<\/strong>, contre <strong>1,6 million<\/strong> un an plus t\u00f4t, tandis que le nombre d&rsquo;utilisateurs financ\u00e9s trimestriels a diminu\u00e9 de <strong>22,2 %<\/strong> pour atteindre <strong>1,4 million<\/strong>. L&rsquo;action EXOD a chut\u00e9 de <strong>86 %<\/strong> au cours des 12 derniers mois et se n\u00e9gociait pr\u00e8s de <strong>7,71 dollars<\/strong> au moment du d\u00e9p\u00f4t du rapport du premier trimestre.<\/p>\n<p>La soci\u00e9t\u00e9 se repositionne en tant que plateforme de paiements native \u00e0 la crypto, plut\u00f4t qu&rsquo;en tant que simple fournisseur de portefeuille. La suite <strong>XO Cash<\/strong> et <strong>Exodus Pay<\/strong>, combin\u00e9es \u00e0 l&rsquo;infrastructure de Monavate et Baanx, pourraient permettre \u00e0 Exodus de rivaliser directement avec les offres de stablecoin des fintechs traditionnelles, telles que MoonPay et le PYUSD de PayPal, sur le march\u00e9 des paiements consommateurs.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Exodus Wallet : Ventes de Bitcoins et Acquisition Strat\u00e9gique Exodus Wallet a vendu 1 076 bitcoins au premier trimestre 2026 pour financer son acquisition de 175 millions de dollars de l&rsquo;activit\u00e9 de paiements de W3C. Exodus Movement (NYSE: EXOD), le d\u00e9veloppeur du portefeuille auto-g\u00e9r\u00e9 Exodus, a r\u00e9duit ses avoirs en BTC de 1 704 \u00e0 628 pi\u00e8ces, diminuant ainsi la valeur de sa tr\u00e9sorerie de 149,2 millions de dollars \u00e0 42,8 millions de dollars. Parall\u00e8lement, l&rsquo;entreprise a ajout\u00e9 5 068 tokens Solana durant la m\u00eame p\u00e9riode. Au total, Exodus a r\u00e9alis\u00e9 des ventes de cryptomonnaies s&rsquo;\u00e9levant \u00e0 73,2 millions de<\/p>\n","protected":false},"author":3,"featured_media":15361,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[15],"tags":[9207,11,200,9208,9675,1126,414,2673,115],"class_list":["post-15362","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-bitcoin","tag-baanx","tag-bitcoin","tag-exodus","tag-exodus-movement","tag-m0","tag-moonpay","tag-paypal","tag-paypal-usd","tag-solana"],"yoast_description":"Exodus Wallet a vendu 1 076 bitcoins au premier trimestre 2026 dans le cadre de son acquisition de 175 millions de dollars de l'activit\u00e9 de paiements de W3C, marquant un tournant vers les paiements en cryptomonnaie.","_links":{"self":[{"href":"https:\/\/satoshibrother.com\/fr\/wp-json\/wp\/v2\/posts\/15362","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/satoshibrother.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/satoshibrother.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/satoshibrother.com\/fr\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/satoshibrother.com\/fr\/wp-json\/wp\/v2\/comments?post=15362"}],"version-history":[{"count":0,"href":"https:\/\/satoshibrother.com\/fr\/wp-json\/wp\/v2\/posts\/15362\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/satoshibrother.com\/fr\/wp-json\/wp\/v2\/media\/15361"}],"wp:attachment":[{"href":"https:\/\/satoshibrother.com\/fr\/wp-json\/wp\/v2\/media?parent=15362"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/satoshibrother.com\/fr\/wp-json\/wp\/v2\/categories?post=15362"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/satoshibrother.com\/fr\/wp-json\/wp\/v2\/tags?post=15362"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}