{"id":15366,"date":"2026-05-13T07:22:29","date_gmt":"2026-05-13T07:22:29","guid":{"rendered":"https:\/\/satoshibrother.com\/fr\/un-hacker-blanchit-activement-des-cryptomonnaies-volees-apres-avoir-exploite-un-fournisseur-de-liquidite-pour-67-millions-de-dollars-peckshield\/"},"modified":"2026-05-13T07:22:29","modified_gmt":"2026-05-13T07:22:29","slug":"un-hacker-blanchit-activement-des-cryptomonnaies-volees-apres-avoir-exploite-un-fournisseur-de-liquidite-pour-67-millions-de-dollars-peckshield","status":"publish","type":"post","link":"https:\/\/satoshibrother.com\/fr\/un-hacker-blanchit-activement-des-cryptomonnaies-volees-apres-avoir-exploite-un-fournisseur-de-liquidite-pour-67-millions-de-dollars-peckshield\/","title":{"rendered":"Un hacker blanchit activement des cryptomonnaies vol\u00e9es apr\u00e8s avoir exploit\u00e9 un fournisseur de liquidit\u00e9 pour 6,7 millions de dollars : PeckShield"},"content":{"rendered":"<h2>Incident de Vol chez TrustedVolumes<\/h2>\n<p>Un hacker a commenc\u00e9 \u00e0 <strong>blanchir des actifs num\u00e9riques<\/strong> issus du vol de <strong>6,7 millions de dollars<\/strong> aupr\u00e8s du fournisseur de liquidit\u00e9 <strong>TrustedVolumes<\/strong>, selon la soci\u00e9t\u00e9 de cybers\u00e9curit\u00e9 <strong>PeckShield<\/strong>. Cette derni\u00e8re indique que de nouvelles donn\u00e9es montrent que le hacker a commenc\u00e9 \u00e0 d\u00e9placer des centaines de milliers de dollars en <em>Ethereum (ETH)<\/em>.<\/p>\n<blockquote>\n<p>\u00ab\u00a0L&rsquo;exploitant de TrustedVolumes a blanchi 278 000 $ de fonds vol\u00e9s jusqu&rsquo;\u00e0 pr\u00e9sent : il a d\u00e9pos\u00e9 10,2 ETH (23 600 $) sur TornadoCash et blanchi 110 ETH (250 000 $) via THORChain vers BTC. Il a \u00e9galement tent\u00e9 de d\u00e9poser 0,5 ETH sur Railgun, mais a chang\u00e9 d&rsquo;avis et l&rsquo;a renvoy\u00e9. TrustedVolumes a \u00e9t\u00e9 exploit\u00e9 pour environ 6,7 millions de dollars le 7 mai.\u00a0\u00bb<\/p>\n<\/blockquote>\n<p>TrustedVolumes d\u00e9clare qu&rsquo;il est pr\u00eat \u00e0 <strong>n\u00e9gocier une r\u00e9solution<\/strong> avec le hacker. La soci\u00e9t\u00e9 liste \u00e9galement trois adresses de portefeuille, dont deux d\u00e9tiennent environ <strong>3 millions de dollars<\/strong> et une <strong>700 000 $<\/strong> en actifs cryptographiques vol\u00e9s.<\/p>\n<blockquote>\n<p>\u00ab\u00a0Nous avons r\u00e9cemment \u00e9t\u00e9 exploit\u00e9s&#8230; Nous sommes ouverts \u00e0 une communication constructive concernant une prime de bug et une r\u00e9solution mutuellement acceptable.\u00a0\u00bb<\/p>\n<\/blockquote>\n<h2>Analyse de l&rsquo;Exploitation<\/h2>\n<p>La soci\u00e9t\u00e9 de s\u00e9curit\u00e9 blockchain <strong>QuillAudits<\/strong> indique que le hacker a pu siphonner des millions en une seule transaction en exploitant un <strong>d\u00e9faut de conception<\/strong> dans le syst\u00e8me de r\u00e8glement de commandes personnalis\u00e9 de la plateforme.<\/p>\n<p>\u00ab\u00a0TrustedVolumes fonctionne comme un market maker et un r\u00e9solveur 1inch, fournissant de la liquidit\u00e9 on-chain via un proxy de Demande de Cotation (RFQ) personnalis\u00e9. Dans un mod\u00e8le RFQ, un maker pr\u00e9-signe des ordres, en citant un prix sp\u00e9cifique pour une paire de tokens. Un taker pr\u00e9sente cette citation sign\u00e9e au contrat de r\u00e8glement, qui v\u00e9rifie la signature et ex\u00e9cute l&rsquo;\u00e9change de mani\u00e8re atomique. Le syst\u00e8me repose sur trois garanties fonctionnant en concert : le maker doit avoir autoris\u00e9 qui peut signer des ordres en son nom, chaque ordre sign\u00e9 doit \u00eatre rempli une seule fois (protection contre la r\u00e9p\u00e9tition), et la source de token pour le remplissage doit \u00eatre l&rsquo;inventaire authentifi\u00e9 du maker, et non une adresse tierce arbitraire. Dans l&rsquo;impl\u00e9mentation de TrustedVolumes, les trois garanties ont \u00e9chou\u00e9 simultan\u00e9ment, et l&rsquo;attaquant en a profit\u00e9 dans une seule transaction compos\u00e9e.\u00a0\u00bb<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Incident de Vol chez TrustedVolumes Un hacker a commenc\u00e9 \u00e0 blanchir des actifs num\u00e9riques issus du vol de 6,7 millions de dollars aupr\u00e8s du fournisseur de liquidit\u00e9 TrustedVolumes, selon la soci\u00e9t\u00e9 de cybers\u00e9curit\u00e9 PeckShield. Cette derni\u00e8re indique que de nouvelles donn\u00e9es montrent que le hacker a commenc\u00e9 \u00e0 d\u00e9placer des centaines de milliers de dollars en Ethereum (ETH). \u00ab\u00a0L&rsquo;exploitant de TrustedVolumes a blanchi 278 000 $ de fonds vol\u00e9s jusqu&rsquo;\u00e0 pr\u00e9sent : il a d\u00e9pos\u00e9 10,2 ETH (23 600 $) sur TornadoCash et blanchi 110 ETH (250 000 $) via THORChain vers BTC. Il a \u00e9galement tent\u00e9 de d\u00e9poser 0,5<\/p>\n","protected":false},"author":3,"featured_media":15365,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[15,64],"tags":[2045,11,13,65,1525,1968,63,2038],"class_list":["post-15366","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-bitcoin","category-hack","tag-1inch-network","tag-bitcoin","tag-ethereum","tag-hack","tag-peckshield","tag-railgun","tag-thorchain","tag-tornado-cash"],"yoast_description":"Un hacker blanchit 6,7 millions de dollars en cryptomonnaies vol\u00e9es de TrustedVolumes, d\u00e9pla\u00e7ant de l'ETH via TornadoCash et THORChain, selon PeckShield.","_links":{"self":[{"href":"https:\/\/satoshibrother.com\/fr\/wp-json\/wp\/v2\/posts\/15366","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/satoshibrother.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/satoshibrother.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/satoshibrother.com\/fr\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/satoshibrother.com\/fr\/wp-json\/wp\/v2\/comments?post=15366"}],"version-history":[{"count":0,"href":"https:\/\/satoshibrother.com\/fr\/wp-json\/wp\/v2\/posts\/15366\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/satoshibrother.com\/fr\/wp-json\/wp\/v2\/media\/15365"}],"wp:attachment":[{"href":"https:\/\/satoshibrother.com\/fr\/wp-json\/wp\/v2\/media?parent=15366"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/satoshibrother.com\/fr\/wp-json\/wp\/v2\/categories?post=15366"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/satoshibrother.com\/fr\/wp-json\/wp\/v2\/tags?post=15366"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}