{"id":18010,"date":"2026-09-01T15:12:12","date_gmt":"2026-09-01T15:12:12","guid":{"rendered":"https:\/\/satoshibrother.com\/fr\/ethena-pay-lance-sa-version-beta-avec-des-taux-allant-jusqua-6\/"},"modified":"2026-09-01T15:12:12","modified_gmt":"2026-09-01T15:12:12","slug":"ethena-pay-lance-sa-version-beta-avec-des-taux-allant-jusqua-6","status":"publish","type":"post","link":"https:\/\/satoshibrother.com\/fr\/ethena-pay-lance-sa-version-beta-avec-des-taux-allant-jusqua-6\/","title":{"rendered":"Ethena Pay lance sa version b\u00eata avec des taux allant jusqu&rsquo;\u00e0 6 %"},"content":{"rendered":"<h2>Introduction \u00e0 Ethena Pay<\/h2>\n<p><strong>Ethena<\/strong> a lanc\u00e9 <strong>Ethena Pay<\/strong> en version b\u00eata pour 400 utilisateurs pr\u00e9coces, offrant des paiements en <strong>USDe<\/strong>, un r\u00e8glement via <strong>Avalanche<\/strong> et des taux de r\u00e9compense annuels allant jusqu&rsquo;\u00e0 <strong>6 %<\/strong> dans une application mobile en auto-garde. Dans une annonce de lancement, Ethena a pr\u00e9cis\u00e9 qu&rsquo;Ethena Pay commencera avec un groupe d&rsquo;acc\u00e8s anticip\u00e9 de 400 utilisateurs, avant d&rsquo;ajouter de nouveaux participants chaque semaine. La soci\u00e9t\u00e9 pr\u00e9voit d&rsquo;\u00e9largir l&rsquo;acc\u00e8s tout au long de septembre, alors que l&rsquo;application passe au-del\u00e0 de sa phase b\u00eata initiale.<\/p>\n<h2>Fonctionnalit\u00e9s de la n\u00e9obanque<\/h2>\n<ul>\n<li><strong>Remboursement<\/strong> sur les d\u00e9penses par carte \u00e0 <strong>5,0 %<\/strong><\/li>\n<li>Taux d&rsquo;\u00e9pargne en dollars de <strong>6,0 %<\/strong>, parmi les meilleurs de sa cat\u00e9gorie<\/li>\n<li><strong>Transferts d&rsquo;argent mondiaux<\/strong> instantan\u00e9s, gratuits et sans fronti\u00e8res<\/li>\n<li>Onramps mondiaux gratuits en <strong>USD<\/strong>, <strong>GBP<\/strong>, <strong>EUR<\/strong> et <strong>FX local<\/strong><\/li>\n<li>Comptes d&rsquo;\u00e9pargne multi-devises \u00e0 hauts rendements<\/li>\n<\/ul>\n<p>Disponible sur <strong>iOS<\/strong>, l&rsquo;application combine un portefeuille crypto en auto-garde avec des virements bancaires, des onramps fiat et une carte de paiement <strong>Visa<\/strong>. Le solde en dollars d&rsquo;un utilisateur est conserv\u00e9 en <strong>USDe<\/strong>, le dollar synth\u00e9tique d&rsquo;Ethena, tandis qu&rsquo;Avalanche traite les transferts, les achats et le r\u00e8glement derri\u00e8re l&rsquo;interface utilisateur de l&rsquo;application.<\/p>\n<h2>Transferts et frais<\/h2>\n<p>Les utilisateurs peuvent recevoir des fiat via des d\u00e9tails de num\u00e9ro de compte bancaire international attribu\u00e9s ou transf\u00e9rer des cryptomonnaies directement vers leurs portefeuilles. Dans les deux cas, le solde re\u00e7u appara\u00eet comme <strong>USDe<\/strong>. Les retraits envoy\u00e9s vers des comptes bancaires externes peuvent \u00eatre convertis dans la devise locale du destinataire, selon Ethena. Les paiements entre utilisateurs d&rsquo;Ethena Pay peuvent \u00e9galement \u00eatre envoy\u00e9s via un nom d&rsquo;utilisateur ou un tag de paiement, au lieu d&rsquo;une adresse blockchain.<\/p>\n<blockquote>\n<p>Ethena a d\u00e9clar\u00e9 que les transferts entre utilisateurs de l&rsquo;application ne comportent aucun frais, tandis que les virements bancaires libell\u00e9s en dollars am\u00e9ricains, euros et livres sterling sont \u00e9galement gratuits.<\/p>\n<\/blockquote>\n<p>D&rsquo;autres virements bancaires peuvent co\u00fbter entre <strong>0,05 %<\/strong> et <strong>0,1 %<\/strong>.<\/p>\n<h2>Disponibilit\u00e9 et r\u00e9compenses<\/h2>\n<p>La version b\u00eata est disponible dans <strong>49 pays<\/strong> d&rsquo;Am\u00e9rique latine, des Cara\u00efbes, d&rsquo;Asie, du Moyen-Orient, d&rsquo;Afrique et d&rsquo;Oc\u00e9anie. La liste des march\u00e9s soutenus par Ethena Pay comprend des pays tels que le <strong>Br\u00e9sil<\/strong>, le <strong>Mexique<\/strong>, l&rsquo;<strong>Australie<\/strong>, le <strong>Japon<\/strong>, <strong>Singapour<\/strong>, les <strong>\u00c9mirats Arabes Unis<\/strong>, le <strong>Kenya<\/strong> et l&rsquo;<strong>Afrique du Sud<\/strong>, bien que les produits individuels restent soumis aux r\u00e8gles d&rsquo;\u00e9ligibilit\u00e9 locales.<\/p>\n<p>Ethena Pay divise ses r\u00e9compenses de solde en niveaux <strong>Standard<\/strong>, <strong>Pro<\/strong> et <strong>VIP<\/strong>. Les utilisateurs Standard peuvent recevoir un taux annuel total allant jusqu&rsquo;\u00e0 <strong>5 %<\/strong> sur les soldes \u00e9ligibles plafonn\u00e9s \u00e0 <strong>5 000 $<\/strong>. Les utilisateurs Pro peuvent recevoir jusqu&rsquo;\u00e0 <strong>6 %<\/strong> sur un solde \u00e9ligible maximum de <strong>15 000 $<\/strong>, tandis que le niveau VIP applique le m\u00eame taux de <strong>6 %<\/strong> jusqu&rsquo;\u00e0 <strong>50 000 $<\/strong>.<\/p>\n<h2>Conditions et restrictions<\/h2>\n<p>Malgr\u00e9 l&rsquo;affichage du taux orient\u00e9 consommateur de l&rsquo;application, les conditions d&rsquo;Ethena Pay d\u00e9crivent le <strong>Daily Boost<\/strong> comme un incitatif promotionnel discr\u00e9tionnaire plut\u00f4t que comme un int\u00e9r\u00eat, un rendement ou un produit de d\u00e9p\u00f4t. La soci\u00e9t\u00e9 indique \u00e9galement que le solde et les r\u00e9compenses associ\u00e9es ne sont pas couverts par la <strong>Federal Deposit Insurance Corporation<\/strong> des \u00c9tats-Unis ou tout autre programme d&rsquo;assurance de d\u00e9p\u00f4t soutenu par le gouvernement.<\/p>\n<p>L&rsquo;adh\u00e9sion standard est gratuite. L&rsquo;acc\u00e8s Pro peut \u00eatre obtenu en verrouillant <strong>2 000 $<\/strong> d&rsquo;<strong>ENA<\/strong> ou en r\u00e9f\u00e9rant <strong>10 utilisateurs<\/strong> \u00e9ligibles, tandis que l&rsquo;adh\u00e9sion VIP n\u00e9cessite <strong>10 000 $<\/strong> d&rsquo;<strong>ENA<\/strong> verrouill\u00e9s ou <strong>50 r\u00e9f\u00e9rences<\/strong>.<\/p>\n<h2>Conclusion<\/h2>\n<p>Ethena Pay Ltd., une soci\u00e9t\u00e9 de logiciels enregistr\u00e9e \u00e0 Malte, d\u00e9clare qu&rsquo;elle n&rsquo;op\u00e8re pas en tant que banque, courtier, conseiller en investissement ou entreprise de services mon\u00e9taires. Des fournisseurs tiers fournissent les services financiers accessibles via l&rsquo;application. Ethena Pay dit qu&rsquo;elle ne peut pas acc\u00e9der aux actifs des clients ou restaurer un portefeuille lorsque l&rsquo;utilisateur perd les informations d&rsquo;identification n\u00e9cessaires pour y acc\u00e9der.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Introduction \u00e0 Ethena Pay Ethena a lanc\u00e9 Ethena Pay en version b\u00eata pour 400 utilisateurs pr\u00e9coces, offrant des paiements en USDe, un r\u00e8glement via Avalanche et des taux de r\u00e9compense annuels allant jusqu&rsquo;\u00e0 6 % dans une application mobile en auto-garde. Dans une annonce de lancement, Ethena a pr\u00e9cis\u00e9 qu&rsquo;Ethena Pay commencera avec un groupe d&rsquo;acc\u00e8s anticip\u00e9 de 400 utilisateurs, avant d&rsquo;ajouter de nouveaux participants chaque semaine. La soci\u00e9t\u00e9 pr\u00e9voit d&rsquo;\u00e9largir l&rsquo;acc\u00e8s tout au long de septembre, alors que l&rsquo;application passe au-del\u00e0 de sa phase b\u00eata initiale. Fonctionnalit\u00e9s de la n\u00e9obanque Remboursement sur les d\u00e9penses par carte \u00e0 5,0 %<\/p>\n","protected":false},"author":3,"featured_media":18009,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[6],"tags":[199,480,606,345,2534,13,4829,35,4180,621,469,1533,804,80,585],"class_list":["post-18010","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-ethereum","tag-australia","tag-avalanche","tag-brazil","tag-ethena","tag-ethena-usde","tag-ethereum","tag-falconx","tag-japan","tag-kenya","tag-mexico","tag-singapore","tag-south-africa","tag-the-block","tag-uae","tag-visa"],"yoast_description":"Ethena Pay a lanc\u00e9 sa version b\u00eata, offrant des paiements en USDe avec des r\u00e9compenses annuelles allant jusqu'\u00e0 6 % \u00e0 400 utilisateurs pr\u00e9coces via une application en auto-garde.","_links":{"self":[{"href":"https:\/\/satoshibrother.com\/fr\/wp-json\/wp\/v2\/posts\/18010","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/satoshibrother.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/satoshibrother.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/satoshibrother.com\/fr\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/satoshibrother.com\/fr\/wp-json\/wp\/v2\/comments?post=18010"}],"version-history":[{"count":0,"href":"https:\/\/satoshibrother.com\/fr\/wp-json\/wp\/v2\/posts\/18010\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/satoshibrother.com\/fr\/wp-json\/wp\/v2\/media\/18009"}],"wp:attachment":[{"href":"https:\/\/satoshibrother.com\/fr\/wp-json\/wp\/v2\/media?parent=18010"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/satoshibrother.com\/fr\/wp-json\/wp\/v2\/categories?post=18010"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/satoshibrother.com\/fr\/wp-json\/wp\/v2\/tags?post=18010"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}