{"id":13245,"date":"2026-02-09T13:56:07","date_gmt":"2026-02-09T13:56:07","guid":{"rendered":"https:\/\/satoshibrother.com\/it\/errore-costoso-181000-in-btc-inviati-misteriosamente-al-wallet-di-satoshi-nakamoto-u-today\/"},"modified":"2026-02-09T13:56:07","modified_gmt":"2026-02-09T13:56:07","slug":"errore-costoso-181000-in-btc-inviati-misteriosamente-al-wallet-di-satoshi-nakamoto-u-today","status":"publish","type":"post","link":"https:\/\/satoshibrother.com\/it\/errore-costoso-181000-in-btc-inviati-misteriosamente-al-wallet-di-satoshi-nakamoto-u-today\/","title":{"rendered":"Errore Costoso? $181,000 in BTC Inviati Misteriosamente al Wallet di Satoshi Nakamoto &#8211; U.Today"},"content":{"rendered":"<h2>Trasferimento di BTC a Satoshi Nakamoto<\/h2>\n<p>Un mittente sconosciuto ha trasferito <strong>2.565 BTC<\/strong>, del valore di <strong>$181,000<\/strong>, all&#8217;indirizzo <em>Genesis<\/em> di Satoshi Nakamoto nel fine settimana, secondo i dati forniti da Arkham. La peculiarit\u00e0 di questo trasferimento \u00e8 che i fondi sono <strong>quasi sicuramente irrecuperabili<\/strong>, poich\u00e9 non ci sono stati deflussi dai wallet di Satoshi dal 2010 a oggi.<\/p>\n<h2>Possibili motivazioni del trasferimento<\/h2>\n<p>Ci si chiede se il trasferimento di una somma cos\u00ec significativa di BTC sia stato un <strong>errore onesto<\/strong>, dovuto a un possibile errore di copia dell&#8217;indirizzo, o se sia stato <strong>intenzionale<\/strong>, con il mittente che desidera &#8220;bruciare&#8221; le proprie monete. Nelle ultime ore ci sono stati lievi afflussi nei wallet di Satoshi, ma di entit\u00e0 molto ridotta \u2014 nell&#8217;ordine di <strong>$2 a $54<\/strong> in BTC, probabilmente trasferimenti di spam.<\/p>\n<h2>La riserva di Satoshi Nakamoto<\/h2>\n<p>Tuttavia, il trasferimento di <strong>$181,000<\/strong> in BTC nel fine settimana si distingue per l&#8217;importo considerevole. Si stima che Satoshi Nakamoto detenga oltre <strong>un milione di BTC<\/strong>; secondo i dati di Arkham, la riserva di BTC del creatore pseudonimo di Bitcoin ammonta a <strong>1.096 milioni di BTC<\/strong>, attualmente valutati <strong>$75.36 miliardi<\/strong>. Questo intero importo proviene da Bitcoin estratti tra il 2009 e il 2010 ed \u00e8 conservato in <strong>22,000 indirizzi<\/strong>.<\/p>\n<h2>Stabilit\u00e0 della riserva di Bitcoin<\/h2>\n<p>Nonostante l&#8217;immenso valore, la riserva di Bitcoin di Satoshi \u00e8 rimasta <strong>intatta dal 2010<\/strong>, senza alcun BTC trasferito fino ad oggi. Gli ultimi trasferimenti noti dai wallet di Satoshi Nakamoto risalgono a <strong>16 anni fa<\/strong>, e recenti speculazioni su vendite di Bitcoin attribuite al creatore di Bitcoin si sono rivelate false.<\/p>\n<h2>Situazione attuale del mercato<\/h2>\n<p>Attualmente, Bitcoin \u00e8 in ribasso, scendendo del <strong>2.65%<\/strong> nelle ultime 24 ore a <strong>$68,761<\/strong>, mentre il mercato delle criptovalute pi\u00f9 ampio ha affrontato nuove vendite luned\u00ec, con <strong>$361 milioni<\/strong> liquidati. Dopo un forte rimbalzo venerd\u00ec, passando da <strong>$60,001<\/strong> a <strong>$71,707<\/strong>, Bitcoin \u00e8 entrato in una fase di trading laterale tra <strong>$67,293<\/strong> e <strong>$72,323<\/strong>, mentre gli investitori attendono sviluppi futuri nei mercati.<\/p>\n<h2>Prossimi eventi economici<\/h2>\n<p>Questa settimana ci si aspetta una serie di dati economici, tra cui il rapporto sui <strong>nonfarm payrolls<\/strong> di gennaio, ritardato, e la lettura dell&#8217;indice dei <strong>prezzi al consumo<\/strong> di gennaio, anch&#8217;esso posticipato a causa della chiusura programmata per venerd\u00ec mattina. Oltre a questi rapporti, gli investitori attenderanno le <strong>vendite al dettaglio<\/strong> di dicembre marted\u00ec e le <strong>richieste settimanali di sussidi di disoccupazione<\/strong> gioved\u00ec.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Trasferimento di BTC a Satoshi Nakamoto Un mittente sconosciuto ha trasferito 2.565 BTC, del valore di $181,000, all&#8217;indirizzo Genesis di Satoshi Nakamoto nel fine settimana, secondo i dati forniti da Arkham. La peculiarit\u00e0 di questo trasferimento \u00e8 che i fondi sono quasi sicuramente irrecuperabili, poich\u00e9 non ci sono stati deflussi dai wallet di Satoshi dal 2010 a oggi. Possibili motivazioni del trasferimento Ci si chiede se il trasferimento di una somma cos\u00ec significativa di BTC sia stato un errore onesto, dovuto a un possibile errore di copia dell&#8217;indirizzo, o se sia stato intenzionale, con il mittente che desidera &#8220;bruciare&#8221; le<\/p>\n","protected":false},"author":3,"featured_media":13244,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[15],"tags":[341,11,558],"class_list":["post-13245","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-bitcoin","tag-arkham","tag-bitcoin","tag-satoshi-nakamoto"],"yoast_description":"Un trasferimento misterioso di $181,000 in BTC al wallet di Satoshi Nakamoto solleva interrogativi sulla sua intenzione, segnando un incidente notevole nel mondo delle criptovalute.","_links":{"self":[{"href":"https:\/\/satoshibrother.com\/it\/wp-json\/wp\/v2\/posts\/13245","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/satoshibrother.com\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/satoshibrother.com\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/satoshibrother.com\/it\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/satoshibrother.com\/it\/wp-json\/wp\/v2\/comments?post=13245"}],"version-history":[{"count":0,"href":"https:\/\/satoshibrother.com\/it\/wp-json\/wp\/v2\/posts\/13245\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/satoshibrother.com\/it\/wp-json\/wp\/v2\/media\/13244"}],"wp:attachment":[{"href":"https:\/\/satoshibrother.com\/it\/wp-json\/wp\/v2\/media?parent=13245"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/satoshibrother.com\/it\/wp-json\/wp\/v2\/categories?post=13245"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/satoshibrother.com\/it\/wp-json\/wp\/v2\/tags?post=13245"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}