{"id":17033,"date":"2026-07-15T19:54:14","date_gmt":"2026-07-15T19:54:14","guid":{"rendered":"https:\/\/satoshibrother.com\/it\/cose-il-bip-110-e-perche-sta-dividendo-la-comunita-bitcoin\/"},"modified":"2026-07-15T19:54:14","modified_gmt":"2026-07-15T19:54:14","slug":"cose-il-bip-110-e-perche-sta-dividendo-la-comunita-bitcoin","status":"publish","type":"post","link":"https:\/\/satoshibrother.com\/it\/cose-il-bip-110-e-perche-sta-dividendo-la-comunita-bitcoin\/","title":{"rendered":"Cos&#8217;\u00e8 il BIP-110 e perch\u00e9 sta dividendo la comunit\u00e0 Bitcoin?"},"content":{"rendered":"<h2>Introduzione alla Proposta di Modifica delle Regole di Consenso di Bitcoin<\/h2>\n<p>Una proposta per modificare le <strong>regole di consenso di Bitcoin<\/strong> ha diviso sviluppatori, miner, aziende e utenti su come la rete dovrebbe evolversi e chi dovrebbe decidere. La disputa ruota attorno al <strong>Bitcoin Improvement Proposal 110<\/strong>, o <em>BIP-110<\/em>.<\/p>\n<h2>Dettagli del BIP-110<\/h2>\n<p>Se implementato, il BIP-110 limiterebbe temporaneamente diversi metodi utilizzati per incorporare dati arbitrari nelle transazioni Bitcoin. I sostenitori affermano che la proposta ridurrebbe lo <strong>spam sulla blockchain<\/strong> e rafforzerebbe il ruolo di Bitcoin come moneta, mentre i critici sostengono che essa rifiuterebbe transazioni valide e potrebbe dividere la rete.<\/p>\n<h2>Reazioni e Opinioni<\/h2>\n<p>Il dibattito ha suscitato reazioni da parte di figure di spicco come lo sviluppatore di Bitcoin <strong>Luke Dashjr<\/strong>, il CEO di Blockstream <strong>Adam Back<\/strong>, il presidente esecutivo di Strategy <strong>Michael Saylor<\/strong>, il Chief Security Officer di Casa <strong>Jameson Lopp<\/strong> e l&#8217;attivista Bitcoin <strong>Samson Mow<\/strong>.<\/p>\n<blockquote>\n<p>&#8220;Ci sono 110 cose pi\u00f9 pericolose per Bitcoin dello spam. Il BIP-110 trasforma una disputa sullo spam in un cambiamento di consenso che invaliderebbe alcune transazioni attualmente valide e che pagano commissioni,&#8221; ha scritto Saylor su X.<\/p>\n<\/blockquote>\n<h2>Implicazioni Tecniche del BIP-110<\/h2>\n<p>Le transazioni Bitcoin possono includere pi\u00f9 di semplici pagamenti; possono anche trasportare testo, immagini, metadati di token e altre informazioni attraverso script di transazione e dati di testimoni. Come un <strong>soft fork<\/strong>, il BIP-110 inasprirebbe le regole di consenso di Bitcoin limitando diverse tecniche utilizzate per incorporare quei dati.<\/p>\n<p>La proposta limiterebbe la maggior parte dei nuovi output di transazione a <strong>34 byte<\/strong>, ripristinerebbe un limite di <strong>83 byte<\/strong> per gli output OP_RETURN, porrebbe un tetto su alcuni elementi di testimoni a <strong>256 byte<\/strong> e limiterebbe temporaneamente diverse funzionalit\u00e0 di <strong>Taproot<\/strong> comunemente utilizzate per le iscrizioni.<\/p>\n<h2>Critiche al BIP-110<\/h2>\n<p>I critici sostengono che il BIP-110 invaliderebbe alcune transazioni che attualmente sono valide secondo le regole di consenso di Bitcoin e stabilirebbe un precedente per futuri cambiamenti di protocollo. In un post sul blog di febbraio, <strong>Jameson Lopp<\/strong> ha sostenuto che il BIP-110 indebolirebbe due delle propriet\u00e0 distintive di Bitcoin: la <strong>resistenza alla censura<\/strong> e la <strong>prevedibilit\u00e0<\/strong>.<\/p>\n<blockquote>\n<p>&#8220;La forza di Bitcoin risiede nella sua resistenza alla censura e nella prevedibilit\u00e0,&#8221; ha scritto Lopp. &#8220;Il BIP-110 segnala che il protocollo pu\u00f2 essere modificato per censurare transazioni soggettivamente &#8216;indesiderabili&#8217;, erodendo la sua immagine di denaro programmabile senza permessi.&#8221;<\/p>\n<\/blockquote>\n<h2>Situazione Attuale e Prospettive Future<\/h2>\n<p>Il periodo di segnalazione obbligatorio del BIP-110 inizia ad agosto e finora solo l&#8217;<strong>1%<\/strong> dei miner ha mostrato supporto per il BIP-110, secondo il dashboard di monitoraggio della proposta. <strong>Adam Back<\/strong> ha sostenuto che il design decentralizzato di Bitcoin impedisce agli utenti di imporre le proprie preferenze sugli altri e che il suo processo di consenso tecnico \u00e8 intenzionalmente resistente al cambiamento.<\/p>\n<blockquote>\n<p>&#8220;Ora la pillola amara, che purtroppo \u00e8 vera,&#8221; ha scritto Back su X. &#8220;Se non ascolti la ragione, educati, impara, la stessa libert\u00e0 radicale si applica a te: il tuo ricorso senza permessi \u00e8 unirti e creare un fork.&#8221;<\/p>\n<\/blockquote>\n<h2>Origine della Disputa<\/h2>\n<p>La disputa attuale risale all&#8217;inizio del 2023 con il lancio di <strong>Ordinals<\/strong>, un protocollo creato dallo sviluppatore di Bitcoin <strong>Casey Rodarmor<\/strong> che consente di iscrivere immagini, testo, video e altri contenuti digitali direttamente su singoli satoshi, la pi\u00f9 piccola unit\u00e0 di Bitcoin. Gli Ordinals utilizzano funzionalit\u00e0 introdotte dagli aggiornamenti <strong>SegWit<\/strong> e <strong>Taproot<\/strong> di Bitcoin per creare asset simili a NFT direttamente sulla blockchain di Bitcoin.<\/p>\n<p>Con la crescente popolarit\u00e0 degli Ordinals e dei token <strong>BRC-20<\/strong>, la domanda di spazio nei blocchi di Bitcoin \u00e8 aumentata, facendo salire le commissioni di transazione. I sostenitori affermano che quelle commissioni hanno generato entrate aggiuntive per i miner e hanno rafforzato la sicurezza a lungo termine di Bitcoin.<\/p>\n<h2>Conclusioni e Riflessioni Finali<\/h2>\n<p>Tuttavia, i critici, incluso <strong>Dashjr<\/strong>, hanno sostenuto che le iscrizioni sfruttano la rete Bitcoin, descrivendole come spam piuttosto che transazioni finanziarie legittime. In un saggio pubblicato su X marted\u00ec intitolato <strong>&#8220;L&#8217;Alleanza Bitcoin&#8221;<\/strong>, <strong>Samson Mow<\/strong> ha sostenuto che i partecipanti a Bitcoin dovrebbero considerarsi un&#8217;alleanza piuttosto che una comunit\u00e0.<\/p>\n<blockquote>\n<p>&#8220;Durante la Guerra delle Dimensioni dei Blocchi, non c&#8217;era mai questa mentalit\u00e0 &#8216;se non sei con noi, sei contro di noi&#8217; dalla nostra parte,&#8221; ha scritto. &#8220;Il campo dei piccoli blocchi non ha mai dovuto costringere nessuno a unirsi. Tutti noi &#8216;capivamo&#8217; e eravamo fiduciosi nella nostra posizione.&#8221;<\/p>\n<\/blockquote>\n<p>Per riferimento, le <strong>Guerre delle Dimensioni dei Blocchi<\/strong> (2015\u20132017) si sono concentrate su se Bitcoin dovesse aumentare il suo limite di dimensione del blocco di 1 MB per elaborare pi\u00f9 transazioni in un singolo blocco sulla rete. Alla fine, il campo dei &#8220;piccoli blocchi&#8221; ha prevalso, con i &#8220;grandi blocchi&#8221; che si sono separati per creare Bitcoin Cash nel 2017 e successivamente Bitcoin SV nel 2018.<\/p>\n<p>Mow ha scritto che condivide le preoccupazioni riguardo allo spam sulla blockchain, ma si oppone al BIP-110 perch\u00e9 crede che i cambiamenti di protocollo richiedano un consenso ampio. Mow ha anche criticato gli sviluppatori di Bitcoin Core per la loro gestione dei recenti cambiamenti nella politica OP_RETURN, sostenendo che entrambe le parti hanno contribuito ad intensificare la disputa.<\/p>\n<blockquote>\n<p>&#8220;Il modo in cui hanno gestito il cambiamento di OP_RETURN era pieno di stupidi errori, dal bandire persone su GitHub agli ACK ninja,&#8221; ha scritto. &#8220;Qualsiasi persona normale avrebbe potuto prevedere la reazione dei plebei. Le persone conservano il loro tempo e valore in Bitcoin. Qualsiasi cosa che sembri minacciare ci\u00f2 far\u00e0 alzare le persone in armi.&#8221;<\/p>\n<\/blockquote>\n","protected":false},"excerpt":{"rendered":"<p>Introduzione alla Proposta di Modifica delle Regole di Consenso di Bitcoin Una proposta per modificare le regole di consenso di Bitcoin ha diviso sviluppatori, miner, aziende e utenti su come la rete dovrebbe evolversi e chi dovrebbe decidere. La disputa ruota attorno al Bitcoin Improvement Proposal 110, o BIP-110. Dettagli del BIP-110 Se implementato, il BIP-110 limiterebbe temporaneamente diversi metodi utilizzati per incorporare dati arbitrari nelle transazioni Bitcoin. I sostenitori affermano che la proposta ridurrebbe lo spam sulla blockchain e rafforzerebbe il ruolo di Bitcoin come moneta, mentre i critici sostengono che essa rifiuterebbe transazioni valide e potrebbe dividere la<\/p>\n","protected":false},"author":3,"featured_media":17032,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[15],"tags":[969,10529,11,971,7585,1524,13,1522,3644,312,2651,4339,115],"class_list":["post-17033","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-bitcoin","tag-adam-back","tag-bip-110","tag-bitcoin","tag-blockstream","tag-brc-20","tag-casa","tag-ethereum","tag-jameson-lopp","tag-luke-dashjr","tag-michael-saylor","tag-ordinals","tag-samson-mow","tag-solana"],"yoast_description":"Il BIP-110 \u00e8 una proposta controversa di Bitcoin che causa divisioni nella comunit\u00e0, concentrandosi sulla limitazione dell'incorporamento di dati nelle transazioni per ridurre lo spam e migliorare la sicurezza.","_links":{"self":[{"href":"https:\/\/satoshibrother.com\/it\/wp-json\/wp\/v2\/posts\/17033","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/satoshibrother.com\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/satoshibrother.com\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/satoshibrother.com\/it\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/satoshibrother.com\/it\/wp-json\/wp\/v2\/comments?post=17033"}],"version-history":[{"count":0,"href":"https:\/\/satoshibrother.com\/it\/wp-json\/wp\/v2\/posts\/17033\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/satoshibrother.com\/it\/wp-json\/wp\/v2\/media\/17032"}],"wp:attachment":[{"href":"https:\/\/satoshibrother.com\/it\/wp-json\/wp\/v2\/media?parent=17033"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/satoshibrother.com\/it\/wp-json\/wp\/v2\/categories?post=17033"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/satoshibrother.com\/it\/wp-json\/wp\/v2\/tags?post=17033"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}