{"id":18019,"date":"2026-09-01T20:52:24","date_gmt":"2026-09-01T20:52:24","guid":{"rendered":"https:\/\/satoshibrother.com\/it\/malware-scoperto-in-19-estensioni-del-browser-google-chrome-hacker-svuotano-criptovalute-e-raccolgono-dati-personali\/"},"modified":"2026-09-01T20:52:24","modified_gmt":"2026-09-01T20:52:24","slug":"malware-scoperto-in-19-estensioni-del-browser-google-chrome-hacker-svuotano-criptovalute-e-raccolgono-dati-personali","status":"publish","type":"post","link":"https:\/\/satoshibrother.com\/it\/malware-scoperto-in-19-estensioni-del-browser-google-chrome-hacker-svuotano-criptovalute-e-raccolgono-dati-personali\/","title":{"rendered":"Malware Scoperto in 19 Estensioni del Browser Google Chrome: Hacker Svuotano Criptovalute e Raccolgono Dati Personali"},"content":{"rendered":"<h2>Scoperta di Malware in Estensioni dei Browser<\/h2>\n<p>I ricercatori di sicurezza hanno scoperto <strong>malware<\/strong> nascosto in <strong>19 estensioni<\/strong> dei browser Chrome ed Edge, utilizzate per svuotare criptovalute dai portafogli digitali e raccogliere password e informazioni personali.<\/p>\n<h2>Obiettivi del Malware<\/h2>\n<p>Questi strumenti hanno preso di mira portafogli <strong>Solana<\/strong>, <strong>Tron<\/strong> ed <strong>EVM<\/strong>, estraendo anche dati da <strong>Facebook<\/strong> e <strong>LinkedIn<\/strong>, oltre alla cronologia del browser e ai dettagli di accesso, come riportato da <em>Socket<\/em>.<\/p>\n<h2>Origine delle Estensioni Compromesse<\/h2>\n<p>Cinque delle estensioni erano inizialmente prodotti legittimi, ma sono state successivamente acquistate dagli attaccanti, che hanno aggiunto malware. Le altre <strong>14<\/strong> sono state create direttamente dagli hacker. Queste estensioni sono state pubblicate inizialmente in forma pulita, per poi ricevere un <strong>aggiornamento dannoso<\/strong> dopo che gli utenti le avevano installate.<\/p>\n<h2>Estensioni Compromesse<\/h2>\n<p>Tra le estensioni compromesse figurano:<\/p>\n<ul>\n<li>Enable Right Click &amp; Copy<\/li>\n<li>RapidLens<\/li>\n<li>QuickLens<\/li>\n<li>Private Crypto News Reader<\/li>\n<li>DeFi Pulse Tracker<\/li>\n<\/ul>\n<h2>Azioni di Google e Raccomandazioni per gli Utenti<\/h2>\n<p>Google ha rimosso le inserzioni di Chrome relative a queste estensioni. Gli utenti che hanno installato una di queste estensioni dovrebbero considerare i propri dati come <strong>compromessi<\/strong> e cambiare immediatamente le proprie <strong>password<\/strong>.<\/p>\n<h2>Informazioni su Socket<\/h2>\n<p><em>Socket<\/em> \u00e8 una societ\u00e0 di sicurezza informatica che monitora il codice open-source e gli add-on del browser per rilevare malware nascosto.<\/p>\n<h2>Segui le Ultime Notizie<\/h2>\n<p>Seguici su <strong>X<\/strong>, <strong>Facebook<\/strong> e <strong>Telegram<\/strong> per non perdere un colpo: iscriviti per ricevere avvisi via email direttamente nella tua casella di posta, coprendo il futuro della finanza, inclusi <strong>macroeconomia<\/strong>, <strong>bitcoin<\/strong>, <strong>ethereum<\/strong>, <strong>criptovalute<\/strong> e <strong>web 3<\/strong>.<\/p>\n<h2>Categorie<\/h2>\n<p>Bitcoin \u2022 Ethereum \u2022 Trading \u2022 Altcoins \u2022 Futuremash \u2022 Financeflux \u2022 Blockchain \u2022 Regolatori \u2022 Truffe \u2022 HodlX \u2022 Comunicato Stampa<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Scoperta di Malware in Estensioni dei Browser I ricercatori di sicurezza hanno scoperto malware nascosto in 19 estensioni dei browser Chrome ed Edge, utilizzate per svuotare criptovalute dai portafogli digitali e raccogliere password e informazioni personali. Obiettivi del Malware Questi strumenti hanno preso di mira portafogli Solana, Tron ed EVM, estraendo anche dati da Facebook e LinkedIn, oltre alla cronologia del browser e ai dettagli di accesso, come riportato da Socket. Origine delle Estensioni Compromesse Cinque delle estensioni erano inizialmente prodotti legittimi, ma sono state successivamente acquistate dagli attaccanti, che hanno aggiunto malware. Le altre 14 sono state create direttamente<\/p>\n","protected":false},"author":3,"featured_media":18018,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[64],"tags":[11,8573,9480,13,3078,949,418,65,7982,9232,115,1923,952,725],"class_list":["post-18019","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-hack","tag-bitcoin","tag-chrome","tag-edge","tag-ethereum","tag-evm","tag-facebook","tag-google","tag-hack","tag-linkedin","tag-socket","tag-solana","tag-telegram","tag-tron","tag-x"],"yoast_description":"I ricercatori di sicurezza hanno scoperto malware in 19 estensioni di Chrome ed Edge, utilizzate per svuotare criptovalute e raccogliere dati personali, generando avvisi urgenti per gli utenti.","_links":{"self":[{"href":"https:\/\/satoshibrother.com\/it\/wp-json\/wp\/v2\/posts\/18019","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/satoshibrother.com\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/satoshibrother.com\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/satoshibrother.com\/it\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/satoshibrother.com\/it\/wp-json\/wp\/v2\/comments?post=18019"}],"version-history":[{"count":0,"href":"https:\/\/satoshibrother.com\/it\/wp-json\/wp\/v2\/posts\/18019\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/satoshibrother.com\/it\/wp-json\/wp\/v2\/media\/18018"}],"wp:attachment":[{"href":"https:\/\/satoshibrother.com\/it\/wp-json\/wp\/v2\/media?parent=18019"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/satoshibrother.com\/it\/wp-json\/wp\/v2\/categories?post=18019"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/satoshibrother.com\/it\/wp-json\/wp\/v2\/tags?post=18019"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}